{"id":10328,"date":"2024-02-09T19:20:57","date_gmt":"2024-02-09T19:20:57","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=10328"},"modified":"2024-02-18T19:29:07","modified_gmt":"2024-02-18T19:29:07","slug":"nova-descoberta-do-weizmann","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/nova-descoberta-do-weizmann\/","title":{"rendered":"Nova descoberta do Weizmann"},"content":{"rendered":"<h3 style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10329\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india.png\" alt=\"Nova descoberta do Weizmann\" width=\"608\" height=\"383\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india.png 670w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india-768x483.png 768w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india-320x201.png 320w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india-480x302.png 480w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2024\/02\/india-800x503.png 800w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><a href=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4217 alignnone\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\" alt=\"\" width=\"27\" height=\"15\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg 27w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel-768x426.jpg 768w\" sizes=\"auto, (max-width: 27px) 100vw, 27px\" \/> <\/a><strong>Nova descoberta do Weizmann<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Pesquisadoras do Departamento de Ci\u00eancias da Terra e Planet\u00e1rias do Weizmann identificaram um complicador at\u00e9 ent\u00e3o desconhecido para prever as chuvas de mon\u00e7\u00e3o que castigam o subcontinente indiano de julho a setembro. S\u00e3o correntes de ar compostas por ar seco e muito frio. Estudando dados de 40 anos, elas descobriram que as intrus\u00f5es secas foram seguidas por um aumento nas chuvas, em alguns casos, de mais de 100%.<\/p>\n<p style=\"font-weight: 400;\">O grupo vai continuar refinando o modelo para melhorar a capacidade de prever chuvas e inunda\u00e7\u00f5es mais severas.<\/p>\n<p>&nbsp;<\/p>\n<p>Saiba mais: <a href=\"https:\/\/wis-wander.weizmann.ac.il\/environment\/when-dryness-intrudes-floods-ensue\" target=\"_blank\" rel=\"noopener\"><em><strong>When Dryness Intrudes, Floods Ensue<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova descoberta do Weizmann &nbsp; Pesquisadoras do Departamento de Ci\u00eancias da Terra e Planet\u00e1rias do Weizmann identificaram um complicador at\u00e9 ent\u00e3o desconhecido para prever as chuvas de mon\u00e7\u00e3o que castigam o subcontinente indiano de julho a setembro. S\u00e3o correntes de ar compostas por ar seco e muito frio. Estudando dados de 40 anos, elas descobriram que as intrus\u00f5es secas foram seguidas por um aumento nas chuvas, em alguns casos, de mais de 100%. O grupo vai continuar refinando o modelo para melhorar a capacidade de prever chuvas e inunda\u00e7\u00f5es mais severas. &nbsp; Saiba mais: When Dryness Intrudes, Floods Ensue<\/p>\n","protected":false},"author":2,"featured_media":10329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-10328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=10328"}],"version-history":[{"count":1,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10328\/revisions"}],"predecessor-version":[{"id":10330,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10328\/revisions\/10330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/10329"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=10328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=10328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=10328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}