{"id":10454,"date":"2024-08-25T23:38:14","date_gmt":"2024-08-25T23:38:14","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=10454"},"modified":"2024-08-27T23:04:12","modified_gmt":"2024-08-27T23:04:12","slug":"camila-freze-baez-nascimento","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/camila-freze-baez-nascimento\/","title":{"rendered":"Camila Freze Baez Nascimento &#8211; Bolsista 2018"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4216\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-brasil.jpg\" sizes=\"auto, (max-width: 27px) 100vw, 27px\" srcset=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-brasil.jpg 27w, http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-brasil-768x426.jpg 768w\" alt=\"\" width=\"27\" height=\"15\" \/> <strong>A cientista ca<\/strong><strong>rioca Camila Freze Baez Nascimento conquista a bolsa de p\u00f3s-doutorado \u201cThe Mora Miriam Rozen Gerber Fellowship\u201d em 2018<\/strong><\/p>\n<p>Camila Freze Baez Nascimento, carioca, 29 anos, \u00e9 a nova bolsista de p\u00f3s-doutorado \u201cThe Mor\u00e1 Miriam Rozen Gerber Fellowship\u201d, para continuar seus estudos no Instituto Weizmann de Ci\u00eancias, Israel. A bolsa integral, destinada exclusivamente a brasileiros, tinha como requisito essencial a excel\u00eancia acad\u00eamica.<\/p>\n<p>Graduada em Biomedicina na \u00a0Universidade Federal Fluminense, UFF, Niter\u00f3i, com Mestrado \u00a0em Microbiologia e Parasitologia Aplicadas na mesma universidade e Doutorado em Medicina (Doen\u00e7as Infecciosas e Parasit\u00e1rias) pela Universidade Federal do Rio de Janeiro, UFRJ, a pesquisa da Camila no Brasil procurava ajudar a melhorar o entendimento cient\u00edfico sobre o papel dos v\u00edrus em c\u00e2nceres de pele.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6096 alignleft\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/03\/Camila-Lab.jpg\" alt=\"\" width=\"207\" height=\"295\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/03\/Camila-Lab.jpg 897w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/03\/Camila-Lab-768x1095.jpg 768w\" sizes=\"auto, (max-width: 207px) 100vw, 207px\" \/>NoInstituto Weizmann, vai ser parte de um grupo pioneiro na identifica\u00e7\u00e3o de um novo tipo de comunica\u00e7\u00e3o das c\u00e9lulas tumorais com as demais: a passagem de RNA \u2013 uma descoberta que abriu uma Infinidade de possibilidades de pesquisa. O laborat\u00f3rio de \u201cTr\u00e1fego de RNAm e de prote\u00ednas\u201d (\u201cmRNA and protein trafficking\u201d ) \u00e9 liderado pelo prof. Jeffrey Gerst do Departamento de Gen\u00e9tica Molecular. \u201cNossa pesquisa pretende investigar se o RNA transferido de uma c\u00e9lula para outra influenciaria as fun\u00e7\u00f5es da c\u00e9lula que o recebeu e, se no caso de transfer\u00eancia de RNAs envolvidos com o desenvolvimento tumoral, haveria a transforma\u00e7\u00e3o de c\u00e9lulas saud\u00e1veis em c\u00e9lulas tumorais. Essa pesquisa \u00e9 inovadora em muitos aspectos e poder\u00e1, por exemplo, indicar novos caminhos terap\u00eauticos para o c\u00e2ncer.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cientista carioca Camila Freze Baez Nascimento conquista a bolsa de p\u00f3s-doutorado \u201cThe Mora Miriam Rozen Gerber Fellowship\u201d em 2018 Camila Freze Baez Nascimento, carioca, 29 anos, \u00e9 a nova bolsista de p\u00f3s-doutorado \u201cThe Mor\u00e1 Miriam Rozen Gerber Fellowship\u201d, para continuar seus estudos no Instituto Weizmann de Ci\u00eancias, Israel. A bolsa integral, destinada exclusivamente a brasileiros, tinha como requisito essencial a excel\u00eancia acad\u00eamica. Graduada em Biomedicina na \u00a0Universidade Federal Fluminense, UFF, Niter\u00f3i, com Mestrado \u00a0em Microbiologia e Parasitologia Aplicadas na mesma universidade e Doutorado em Medicina (Doen\u00e7as Infecciosas e Parasit\u00e1rias) pela Universidade Federal do Rio de Janeiro, UFRJ, a pesquisa da Camila no Brasil procurava ajudar a melhorar o entendimento cient\u00edfico sobre o papel dos v\u00edrus em c\u00e2nceres de pele. NoInstituto Weizmann, vai ser parte de um grupo pioneiro na identifica\u00e7\u00e3o de um novo tipo de comunica\u00e7\u00e3o das c\u00e9lulas tumorais com as demais: a passagem de RNA \u2013 uma descoberta que abriu uma Infinidade de possibilidades de pesquisa. O laborat\u00f3rio de \u201cTr\u00e1fego de RNAm e de prote\u00ednas\u201d (\u201cmRNA and protein trafficking\u201d ) \u00e9 liderado pelo prof. Jeffrey Gerst do Departamento de Gen\u00e9tica Molecular. \u201cNossa pesquisa pretende investigar se o RNA transferido de uma c\u00e9lula para outra influenciaria as fun\u00e7\u00f5es da c\u00e9lula que o recebeu e, se no caso de transfer\u00eancia de RNAs envolvidos com o desenvolvimento tumoral, haveria a transforma\u00e7\u00e3o de c\u00e9lulas saud\u00e1veis em c\u00e9lulas tumorais. Essa pesquisa \u00e9 inovadora em muitos aspectos e poder\u00e1, por exemplo, indicar novos caminhos terap\u00eauticos para o c\u00e2ncer.\u201d &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":6096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[426],"tags":[],"class_list":["post-10454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mora-miriam-rozen-gerber-fellowship"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=10454"}],"version-history":[{"count":4,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10454\/revisions"}],"predecessor-version":[{"id":10477,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/10454\/revisions\/10477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/6096"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=10454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=10454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=10454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}