{"id":6214,"date":"2018-07-13T06:47:36","date_gmt":"2018-07-13T06:47:36","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=6214"},"modified":"2018-07-23T14:21:26","modified_gmt":"2018-07-23T14:21:26","slug":"science-tips-97-transmitir-a-geracao-seguinte-gracas-ao-perach","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/science-tips-97-transmitir-a-geracao-seguinte-gracas-ao-perach\/","title":{"rendered":"Science Tips 97 &#8211; Transmitir \u00e0 gera\u00e7\u00e3o seguinte gra\u00e7as ao Perach"},"content":{"rendered":"<div id=\"attachment_6220\" style=\"width: 578px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6220\" class=\" wp-image-6220\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/07\/ScienceTips97-03.jpg\" alt=\"\" width=\"568\" height=\"318\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/07\/ScienceTips97-03.jpg 800w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2018\/07\/ScienceTips97-03-768x430.jpg 768w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><p id=\"caption-attachment-6220\" class=\"wp-caption-text\">(da esquerda para a direita) Ra\u2019anan Parpari e Emanuel (Emil) Eiden<\/p><\/div>\n<h2 style=\"text-align: center;\"><strong>Transmitir \u00e0 gera\u00e7\u00e3o seguinte gra\u00e7as ao Perach<\/strong><\/h2>\n<p>Ao escrever sua tese de doutorado, Emil (Emanuel) Eidin, um estudante do Departamento de Ensino de Ci\u00eancias do Instituto Weizmann de Ci\u00eancia, comec\u0327ou a pensar nas pessoas que ele gostaria de agradecer na se\u00e7\u00e3o de agradecimentos, na parte final da tese. Ele decidiu que algumas das pessoas a quem agradecer seriam os mentores do Perach que o ajudaram quando era crianc\u0327a. Perach \u00e9 um programa nacional de orienta\u00e7\u00e3o estabelecido h\u00e1 mais de 40 anos no Instituto Weizmann, no qual estudantes universit\u00e1rios orientam individualmente as crian\u00e7as desfavorecidas ou com dificuldades escolares. Eidin n\u00e3o se lembrava dos sobrenomes dos mentores que haviam trabalhado com ele, ent\u00e3o enviou um e-mail para os escrit\u00f3rios do Perach na esperan\u00e7a de que algu\u00e9m encontrasse seus antigos mentores.<\/p>\n<p>O e-mail foi publicado no Facebook, onde se tornou viral. E a equipe do Perach encontrou Ra\u2019anan Parpari, o mentor que Eidin lembra de lhe ter mostrado novos mundos ao dar-lhe um livro.<\/p>\n<p>O livro foi Hobbit, de J.R.R. Tolkien, que apresentou o mundo da fantasia ao garoto solit\u00e1rio. Os dois comec\u0327aram a se comunicar pelo Facebook e acabaram se encontrando pessoalmente.<\/p>\n<h3 style=\"text-align: center;\">\u201cNossa esperanc\u0327a e\u0301 que os professores que lerem a nossa histo\u0301ria se sintam inclinados a olhar para os seus alunos de uma maneira um pouco diferente\u201d<\/h3>\n<p>Na escola prim\u00e1ria, Eidin era uma \u201ccrian\u00e7a problem\u00e1tica\u201d, cujas notas eram entre m\u00e9dias a baixas. A reuni\u00e3o foi emotiva: Eidin contou a Parpari o quanto sua ajuda e apoio significaram para ele. \u201cEu vivia num mundo de LEGO, m\u00fasica e livros de Sherlock Holmes\u201d, declarou. \u201cMas na escola, se suas notas n\u00e3o s\u00e3o boas o suficiente, ent\u00e3o voc\u00ea n\u00e3o \u00e9 bom o suficiente. Parpari conseguiu me enxergar, e ver uma pessoa al\u00e9m das minhas notas. E a porta que ele abriu para mim no mundo da fantasia realmente influenciou na minha decis\u00e3o de entrar para a ci\u00eancia.\u201d Parpari se lembra de Emil como uma crian\u00e7a simp\u00e1tica e educada, que se sentia isolada. Ele ajudava com a li\u00e7\u00e3o de casa, mas eles tamb\u00e9m jogavam jogos de fantasia juntos, conversavam e sa\u00edam para caminhar.<\/p>\n<p>Quando Eidin estava na faculdade, ele voltou ao Perach, desta vez para trabalhar como mentor. \u201cNossa esperan\u00e7a\u201d, dizem ambos, \u201c\u00e9 que os professores que lerem a nossa hist\u00f3ria se sintam inclinados a olhar para os seus alunos de uma maneira um pouco diferente, e que mais alunos universit\u00e1rios se sintam inspirados a se juntar ao Perach. Foi por isso que concordamos em contar a nossa hist\u00f3ria.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transmitir \u00e0 gera\u00e7\u00e3o seguinte gra\u00e7as ao Perach Ao escrever sua tese de doutorado, Emil (Emanuel) Eidin, um estudante do Departamento de Ensino de Ci\u00eancias do Instituto Weizmann de Ci\u00eancia, comec\u0327ou a pensar nas pessoas que ele gostaria de agradecer na se\u00e7\u00e3o de agradecimentos, na parte final da tese. Ele decidiu que algumas das pessoas a quem agradecer seriam os mentores do Perach que o ajudaram quando era crianc\u0327a. Perach \u00e9 um programa nacional de orienta\u00e7\u00e3o estabelecido h\u00e1 mais de 40 anos no Instituto Weizmann, no qual estudantes universit\u00e1rios orientam individualmente as crian\u00e7as desfavorecidas ou com dificuldades escolares. Eidin n\u00e3o se lembrava dos sobrenomes dos mentores que haviam trabalhado com ele, ent\u00e3o enviou um e-mail para os escrit\u00f3rios do Perach na esperan\u00e7a de que algu\u00e9m encontrasse seus antigos mentores. O e-mail foi publicado no Facebook, onde se tornou viral. E a equipe do Perach encontrou Ra\u2019anan Parpari, o mentor que Eidin lembra de lhe ter mostrado novos mundos ao dar-lhe um livro. O livro foi Hobbit, de J.R.R. Tolkien, que apresentou o mundo da fantasia ao garoto solit\u00e1rio. Os dois comec\u0327aram a se comunicar pelo Facebook e acabaram se encontrando pessoalmente. \u201cNossa esperanc\u0327a e\u0301 que os professores que lerem a nossa histo\u0301ria se sintam inclinados a olhar para os seus alunos de uma maneira um pouco diferente\u201d Na escola prim\u00e1ria, Eidin era uma \u201ccrian\u00e7a problem\u00e1tica\u201d, cujas notas eram entre m\u00e9dias a baixas. A reuni\u00e3o foi emotiva: Eidin contou a Parpari o quanto sua ajuda e apoio significaram para ele. \u201cEu vivia num mundo de LEGO, m\u00fasica e livros de Sherlock Holmes\u201d, declarou. \u201cMas na escola, se suas notas n\u00e3o s\u00e3o boas o suficiente, ent\u00e3o voc\u00ea n\u00e3o \u00e9 bom o suficiente. Parpari conseguiu me enxergar, e ver uma pessoa al\u00e9m das minhas notas. E a porta que ele abriu para mim no mundo da fantasia realmente influenciou na minha decis\u00e3o de entrar para a ci\u00eancia.\u201d Parpari se lembra de Emil como uma crian\u00e7a simp\u00e1tica e educada, que se sentia isolada. Ele ajudava com a li\u00e7\u00e3o de casa, mas eles tamb\u00e9m jogavam jogos de fantasia juntos, conversavam e sa\u00edam para caminhar. Quando Eidin [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6220,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[50],"tags":[],"class_list":["post-6214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-science-tips"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/6214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=6214"}],"version-history":[{"count":4,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/6214\/revisions"}],"predecessor-version":[{"id":6224,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/6214\/revisions\/6224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/6220"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=6214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=6214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=6214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}