{"id":9295,"date":"2022-06-13T17:51:27","date_gmt":"2022-06-13T17:51:27","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=9295"},"modified":"2022-07-05T18:27:17","modified_gmt":"2022-07-05T18:27:17","slug":"com-tecnologia-de-ultima-geracao-cientistas-descobrem-as-evidencias-mais-antigas-do-uso-controlado-do-fogo","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/com-tecnologia-de-ultima-geracao-cientistas-descobrem-as-evidencias-mais-antigas-do-uso-controlado-do-fogo\/","title":{"rendered":"Com tecnologia de \u00faltima gera\u00e7\u00e3o, cientistas descobrem as evid\u00eancias mais antigas do uso controlado do fogo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9297\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/07\/arqueologia-e1657044097647.png\" alt=\"\" width=\"800\" height=\"442\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4217 aligncenter\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\" alt=\"\" width=\"27\" height=\"15\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg 27w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel-768x426.jpg 768w\" sizes=\"auto, (max-width: 27px) 100vw, 27px\" \/>\u00a0Com tecnologia de \u00faltima gera\u00e7\u00e3o, cientistas descobrem as evid\u00eancias mais antigas do uso controlado do fogo<\/strong><\/p>\n<h5 style=\"text-align: center;\">13.06.2022<\/h5>\n<p dir=\"ltr\">O uso controlado do fogo por antigos homin\u00eddeos dataria de pelo menos um milh\u00e3o de anos, mas as evid\u00eancias arqueol\u00f3gicas mais distantes se remontavam a 500.000 anos atr\u00e1s. A hist\u00f3ria mudou quando pesquisadores do Instituto Weizmann de Ci\u00eancias desenvolveram um m\u00e9todo avan\u00e7ado e inovador para detectar tra\u00e7os n\u00e3o visuais de fogo.<\/p>\n<p dir=\"ltr\">Evron \u00e9 um s\u00edtio arqueol\u00f3gico na Galileia Ocidental descoberto na d\u00e9cada de 1970 e onde os arque\u00f3logos encontraram f\u00f3sseis de animais e ferramentas paleol\u00edticas que datam entre 800.000 e 1 milh\u00e3o de anos atr\u00e1s.\u00a0 Atrav\u00e9s de t\u00e9cnicas da IA, que permitem encontrar padr\u00f5es ocultos, os pesquisadores compararam a composi\u00e7\u00e3o qu\u00edmica dos materiais at\u00e9 o n\u00edvel molecular. Conseguiram assim estimar a temperatura ao qual 26 ferramentas de pedra encontradas no local h\u00e1 quase meio s\u00e9culo foram aquecidas, \u2013 algumas superiores a 600\u00b0C.\u00a0 E, usando uma t\u00e9cnica diferente, descobriram que o dente de um elefante extinto tamb\u00e9m apresentava mudan\u00e7as estruturais resultantes do aquecimento.<\/p>\n<p dir=\"ltr\">Os pesquisadores, liderados pelo Dr. Filipe Natalio do Departamento de Ci\u00eancias Ambientais e Bot\u00e2nicas do WIS, acreditam que este m\u00e9todo avan\u00e7ado e inovador para detectar tra\u00e7os n\u00e3o visuais de fogo vai nos ajudar a entender melhor as origens da hist\u00f3ria humana.<\/p>\n<div><\/div>\n<div><\/div>\n<p>Leia mais:\u00a0<a href=\"https:\/\/wis-wander.weizmann.ac.il\/scientific-archaeology\/heat-weizmann-institute-scientists-uncover-traces-fire-dating-back-least\" target=\"_blank\" rel=\"noopener noreferrer\">The Heat Is On: Weizmann Institute Scientists Uncover Traces of Fire Dating Back At Least 800,000 Years<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0Com tecnologia de \u00faltima gera\u00e7\u00e3o, cientistas descobrem as evid\u00eancias mais antigas do uso controlado do fogo 13.06.2022 O uso controlado do fogo por antigos homin\u00eddeos dataria de pelo menos um milh\u00e3o de anos, mas as evid\u00eancias arqueol\u00f3gicas mais distantes se remontavam a 500.000 anos atr\u00e1s. A hist\u00f3ria mudou quando pesquisadores do Instituto Weizmann de Ci\u00eancias desenvolveram um m\u00e9todo avan\u00e7ado e inovador para detectar tra\u00e7os n\u00e3o visuais de fogo. Evron \u00e9 um s\u00edtio arqueol\u00f3gico na Galileia Ocidental descoberto na d\u00e9cada de 1970 e onde os arque\u00f3logos encontraram f\u00f3sseis de animais e ferramentas paleol\u00edticas que datam entre 800.000 e 1 milh\u00e3o de anos atr\u00e1s.\u00a0 Atrav\u00e9s de t\u00e9cnicas da IA, que permitem encontrar padr\u00f5es ocultos, os pesquisadores compararam a composi\u00e7\u00e3o qu\u00edmica dos materiais at\u00e9 o n\u00edvel molecular. Conseguiram assim estimar a temperatura ao qual 26 ferramentas de pedra encontradas no local h\u00e1 quase meio s\u00e9culo foram aquecidas, \u2013 algumas superiores a 600\u00b0C.\u00a0 E, usando uma t\u00e9cnica diferente, descobriram que o dente de um elefante extinto tamb\u00e9m apresentava mudan\u00e7as estruturais resultantes do aquecimento. Os pesquisadores, liderados pelo Dr. Filipe Natalio do Departamento de Ci\u00eancias Ambientais e Bot\u00e2nicas do WIS, acreditam que este m\u00e9todo avan\u00e7ado e inovador para detectar tra\u00e7os n\u00e3o visuais de fogo vai nos ajudar a entender melhor as origens da hist\u00f3ria humana. Leia mais:\u00a0The Heat Is On: Weizmann Institute Scientists Uncover Traces of Fire Dating Back At Least 800,000 Years &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":9297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[328,57,387,44],"class_list":["post-9295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-arquelogia","tag-israel","tag-usodofogo","tag-weizmann"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=9295"}],"version-history":[{"count":3,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9295\/revisions"}],"predecessor-version":[{"id":9304,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9295\/revisions\/9304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/9297"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=9295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=9295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=9295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}