{"id":9431,"date":"2022-08-04T01:19:21","date_gmt":"2022-08-04T01:19:21","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=9431"},"modified":"2022-11-29T01:26:22","modified_gmt":"2022-11-29T01:26:22","slug":"tem-colite-ulcerativa-ou-doenca-de-crohn","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/tem-colite-ulcerativa-ou-doenca-de-crohn\/","title":{"rendered":"Tem colite ulcerativa ou doen\u00e7a de Crohn?"},"content":{"rendered":"<h3 style=\"text-align: center;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9432 aligncenter\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/11\/doenca-chron-e1669684840161.png\" alt=\"\" width=\"800\" height=\"321\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/11\/doenca-chron-e1669684840161.png 800w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/11\/doenca-chron-e1669684840161-768x308.png 768w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/11\/doenca-chron-e1669684840161-320x128.png 320w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2022\/11\/doenca-chron-e1669684840161-480x192.png 480w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4217\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\" alt=\"\" width=\"27\" height=\"15\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg 27w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel-768x426.jpg 768w\" sizes=\"auto, (max-width: 27px) 100vw, 27px\" \/> Tem colite ulcerativa ou doen\u00e7a de Crohn?<\/b><\/h3>\n<h5 dir=\"ltr\" style=\"text-align: center;\">04.08.22<\/h5>\n<p dir=\"ltr\">Seu pr\u00f3ximo rem\u00e9dio pode ser um cocktail de v\u00edrus. Pesquisadores do Instituto Weizmann de Ci\u00eancias demonstraram a viabilidade de uma terapia que mata as bact\u00e9rias intestinais causadoras de inflama\u00e7\u00e3o. A terapia usa um cocktail de v\u00edrus denominados bacteri\u00f3fagos, que as infectam de forma espec\u00edfica sem danificar os microrganismos saud\u00e1veis. Os ensaios cl\u00ednicos da fase 1 j\u00e1 mostraram que \u00e9 seguro.<\/p>\n<p dir=\"ltr\">&#8220;\u00c9 a primeira abordagem \u2018bala de prata&#8217;, que promete uma supress\u00e3o precisa de micr\u00f3bios intestinais causadores de doen\u00e7as, sem prejudicar o microbioma circundante.&#8221;- disse o Prof. Eran Elinav, do Departamento de Imunologia de Sistemas do Weizmann, que chefiou a equipe de pesquisa. &#8220;Nossa vis\u00e3o \u00e9, eventualmente, desenvolver terapias personalizadas para uma variedade de dist\u00farbios, nos quais ser\u00e3o identificadas em cada paciente as cepas das bact\u00e9rias intestinais causadoras de doen\u00e7as e depois ser\u00e1 definido o coquetel de v\u00edrus bacteri\u00f3fagos que mata apenas essas cepas&#8221;, diz Elinav.<\/p>\n<p dir=\"ltr\">Os estudos para estas doen\u00e7as inflamat\u00f3rias intestinais foram realizado em colabora\u00e7\u00e3o com outros pesquisadores incluindo o BiomX Inc., uma empresa que investe em terapias para bact\u00e9rias patog\u00eanicas com base na pesquisa do WIS,\u00a0 sob licen\u00e7a de Yeda Research &amp; Development Company Ltd., o bra\u00e7o de transfer\u00eancia de tecnologia do Instituto Weizmann de Ci\u00eancias.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">Saiba mais: <em><strong><a href=\"https:\/\/wis-wander.weizmann.ac.il\/life-sciences\/viruses-fight-disease\" target=\"_blank\" rel=\"noopener\">The Viruses That Fight Disease<\/a><\/strong><\/em><\/p>\n<p dir=\"ltr\">\n","protected":false},"excerpt":{"rendered":"<p>Tem colite ulcerativa ou doen\u00e7a de Crohn? 04.08.22 Seu pr\u00f3ximo rem\u00e9dio pode ser um cocktail de v\u00edrus. Pesquisadores do Instituto Weizmann de Ci\u00eancias demonstraram a viabilidade de uma terapia que mata as bact\u00e9rias intestinais causadoras de inflama\u00e7\u00e3o. A terapia usa um cocktail de v\u00edrus denominados bacteri\u00f3fagos, que as infectam de forma espec\u00edfica sem danificar os microrganismos saud\u00e1veis. Os ensaios cl\u00ednicos da fase 1 j\u00e1 mostraram que \u00e9 seguro. &#8220;\u00c9 a primeira abordagem \u2018bala de prata&#8217;, que promete uma supress\u00e3o precisa de micr\u00f3bios intestinais causadores de doen\u00e7as, sem prejudicar o microbioma circundante.&#8221;- disse o Prof. Eran Elinav, do Departamento de Imunologia de Sistemas do Weizmann, que chefiou a equipe de pesquisa. &#8220;Nossa vis\u00e3o \u00e9, eventualmente, desenvolver terapias personalizadas para uma variedade de dist\u00farbios, nos quais ser\u00e3o identificadas em cada paciente as cepas das bact\u00e9rias intestinais causadoras de doen\u00e7as e depois ser\u00e1 definido o coquetel de v\u00edrus bacteri\u00f3fagos que mata apenas essas cepas&#8221;, diz Elinav. Os estudos para estas doen\u00e7as inflamat\u00f3rias intestinais foram realizado em colabora\u00e7\u00e3o com outros pesquisadores incluindo o BiomX Inc., uma empresa que investe em terapias para bact\u00e9rias patog\u00eanicas com base na pesquisa do WIS,\u00a0 sob licen\u00e7a de Yeda Research &amp; Development Company Ltd., o bra\u00e7o de transfer\u00eancia de tecnologia do Instituto Weizmann de Ci\u00eancias. Saiba mais: The Viruses That Fight Disease<\/p>\n","protected":false},"author":2,"featured_media":9432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[216,71,411,410,409,401,57,228,191,44],"class_list":["post-9431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-biotech","tag-ciencia","tag-colite-ulcerativa","tag-doenca-de-crohn","tag-doencas-inflamatorias-intestinais","tag-eranelinav","tag-israel","tag-medicina-personalizada","tag-microbioma","tag-weizmann"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=9431"}],"version-history":[{"count":1,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9431\/revisions"}],"predecessor-version":[{"id":9433,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9431\/revisions\/9433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/9432"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=9431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=9431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=9431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}