{"id":9964,"date":"2023-06-16T00:25:21","date_gmt":"2023-06-16T00:25:21","guid":{"rendered":"http:\/\/amigosdoweizmann.org.br\/stage\/?p=9964"},"modified":"2023-06-29T00:39:20","modified_gmt":"2023-06-29T00:39:20","slug":"um-novo-metodo-de-inteligencia-artificial-pode-melhorar-a-precisao-da-previsao-de-tempestades-de-poeira","status":"publish","type":"post","link":"https:\/\/amigosdoweizmann.org.br\/stage\/um-novo-metodo-de-inteligencia-artificial-pode-melhorar-a-precisao-da-previsao-de-tempestades-de-poeira\/","title":{"rendered":"Um novo m\u00e9todo de intelig\u00eancia artificial pode melhorar a precis\u00e3o da previs\u00e3o de tempestades de poeira"},"content":{"rendered":"<p><a href=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9965\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai.png\" alt=\"\" width=\"920\" height=\"430\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai.png 920w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai-768x358.png 768w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai-320x149.png 320w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai-480x224.png 480w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2023\/06\/ai-800x373.png 800w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/a><\/p>\n<h3 style=\"text-align: center;\"><strong><a href=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4217\" src=\"http:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg\" alt=\"\" width=\"27\" height=\"15\" srcset=\"https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel.jpg 27w, https:\/\/amigosdoweizmann.org.br\/stage\/wp-content\/uploads\/2017\/04\/miniflag-israel-768x426.jpg 768w\" sizes=\"auto, (max-width: 27px) 100vw, 27px\" \/><\/a> Um novo m\u00e9todo de intelig\u00eancia artificial pode melhorar a precis\u00e3o da previs\u00e3o de tempestades de poeira<\/strong><\/h3>\n<h5 style=\"text-align: center;\">16.06.2023<\/h5>\n<p style=\"font-weight: 400;\">Um estudo de pesquisadores do Departamento de Ci\u00eancias da Terra e Planet\u00e1rias do Instituto Weizmann de Ci\u00eancias traz um avan\u00e7o importante na previs\u00e3o de tempestades de poeira. A realiza\u00e7\u00e3o mais significativa desta pesquisa \u00e9 o uso de intelig\u00eancia artificial para escanear uma cole\u00e7\u00e3o grande de dados e estudar os princ\u00edpios f\u00edsicos e os processos atmosf\u00e9ricos de uma maneira antes indispon\u00edvel.<\/p>\n<p style=\"font-weight: 400;\">\u00a0Usando dados coletados de todas as esta\u00e7\u00f5es meteorol\u00f3gicas de Israel nos \u00faltimos 20 anos, previram com sucesso mais de 80% das tempestades de poeira com 24 horas de anteced\u00eancia e cerca de 70%, 48 horas antes. A rede foi treinada com dados de Israel, mas pode, com alguns ajustes, prever tempestades de poeira em outros lugares do mundo. &#8220;Al\u00e9m disso,\u00a0criamos uma arquitetura que pode ajudar a prever outros eventos raros que est\u00e3o ligados a dados meteorol\u00f3gicos, como chuvas extremas ou inunda\u00e7\u00f5es repentinas&#8221;\u00a0, diz Dr. Ron Sarafian.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Saiba mais: <span style=\"color: #00ccff;\"><em><strong><a style=\"color: #00ccff;\" href=\"https:\/\/wis-wander.weizmann.ac.il\/environment\/dust-wind-forecasting-storms-ai\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/wis-wander.weizmann.ac.il\/environment\/dust-wind-forecasting-storms-ai&amp;source=gmail&amp;ust=1688084385723000&amp;usg=AOvVaw1ob27mqd9eB-fAp3tb2uau\">Dust in the Wind: Forecasting Storms with AI<\/a><\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um novo m\u00e9todo de intelig\u00eancia artificial pode melhorar a precis\u00e3o da previs\u00e3o de tempestades de poeira 16.06.2023 Um estudo de pesquisadores do Departamento de Ci\u00eancias da Terra e Planet\u00e1rias do Instituto Weizmann de Ci\u00eancias traz um avan\u00e7o importante na previs\u00e3o de tempestades de poeira. A realiza\u00e7\u00e3o mais significativa desta pesquisa \u00e9 o uso de intelig\u00eancia artificial para escanear uma cole\u00e7\u00e3o grande de dados e estudar os princ\u00edpios f\u00edsicos e os processos atmosf\u00e9ricos de uma maneira antes indispon\u00edvel. \u00a0Usando dados coletados de todas as esta\u00e7\u00f5es meteorol\u00f3gicas de Israel nos \u00faltimos 20 anos, previram com sucesso mais de 80% das tempestades de poeira com 24 horas de anteced\u00eancia e cerca de 70%, 48 horas antes. A rede foi treinada com dados de Israel, mas pode, com alguns ajustes, prever tempestades de poeira em outros lugares do mundo. &#8220;Al\u00e9m disso,\u00a0criamos uma arquitetura que pode ajudar a prever outros eventos raros que est\u00e3o ligados a dados meteorol\u00f3gicos, como chuvas extremas ou inunda\u00e7\u00f5es repentinas&#8221;\u00a0, diz Dr. Ron Sarafian. &nbsp; Saiba mais: Dust in the Wind: Forecasting Storms with AI &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":9965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[152,412,292,57,44],"class_list":["post-9964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-clima","tag-datascience","tag-ia","tag-israel","tag-weizmann"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/comments?post=9964"}],"version-history":[{"count":2,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9964\/revisions"}],"predecessor-version":[{"id":9967,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/posts\/9964\/revisions\/9967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media\/9965"}],"wp:attachment":[{"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/media?parent=9964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/categories?post=9964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amigosdoweizmann.org.br\/stage\/wp-json\/wp\/v2\/tags?post=9964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}